{"id":6064,"date":"2025-05-30T10:41:05","date_gmt":"2025-05-30T08:41:05","guid":{"rendered":"https:\/\/medilinetorino.it\/medilineshop\/prodotto\/batteria-ll-trader-per-iphone-8-batteria-agli-ioni-di-litio-ad-alta-capacita-da-3800-mah-con-strumenti-di-riparazione\/"},"modified":"2025-05-30T10:41:05","modified_gmt":"2025-05-30T08:41:05","slug":"batteria-ll-trader-per-iphone-8-batteria-agli-ioni-di-litio-ad-alta-capacita-da-3800-mah-con-strumenti-di-riparazione","status":"publish","type":"product","link":"https:\/\/medilinetorino.it\/medilineshop\/prodotto\/batteria-ll-trader-per-iphone-8-batteria-agli-ioni-di-litio-ad-alta-capacita-da-3800-mah-con-strumenti-di-riparazione\/","title":{"rendered":"Batteria LL TRADER per iPhone 8, batteria agli ioni di litio ad alta capacit\u00e0 da 3800 mAh con strumenti di riparazione"},"content":{"rendered":"<p><iframe title=\"3800 mAh batteria per iPhone 8, Yodoit aggiornato ad alta capacit\u00e0 Li-ion polimero sostituzione della batteria 0 ciclo con kit completo di strumenti di riparazione e adesivo\" type=\"text\/html\" width=\"500\" height=\"550\" frameborder=\"0\" allowfullscreen style=\"max-width:100%\" src=\"https:\/\/leggi.amazon.it\/kp\/card?preview=inline&#038;linkCode=kpd&#038;ref_=k4w_oembed_DKwipBMDEJdJ87&#038;asin=B0BRN5YKQP&#038;tag=kpembed-20\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[196],"product_tag":[],"class_list":["post-6064","product","type-product","status-publish","product_cat-consumabile","first","outofstock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/medilinetorino.it\/medilineshop\/wp-json\/wp\/v2\/product\/6064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medilinetorino.it\/medilineshop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/medilinetorino.it\/medilineshop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/medilinetorino.it\/medilineshop\/wp-json\/wp\/v2\/comments?post=6064"}],"wp:attachment":[{"href":"https:\/\/medilinetorino.it\/medilineshop\/wp-json\/wp\/v2\/media?parent=6064"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/medilinetorino.it\/medilineshop\/wp-json\/wp\/v2\/product_brand?post=6064"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/medilinetorino.it\/medilineshop\/wp-json\/wp\/v2\/product_cat?post=6064"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/medilinetorino.it\/medilineshop\/wp-json\/wp\/v2\/product_tag?post=6064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}